{"id":858,"date":"2026-06-22T06:11:20","date_gmt":"2026-06-22T06:11:20","guid":{"rendered":"https:\/\/nolabelworld.com\/?page_id=858"},"modified":"2026-06-22T06:52:42","modified_gmt":"2026-06-22T06:52:42","slug":"%e9%9b%b2%e6%bc%ab%e9%9b%aa%e5%b1%b1%e4%ba%ba%e5%ad%97%e6%8b%bc","status":"publish","type":"page","link":"https:\/\/nolabelworld.com\/zh_cn\/%e8%ab%be%e8%90%8a%e5%b1%85spc%e5%9c%b0%e6%9d%bf%e7%b3%bb%e5%88%97\/%e6%9c%a8%e7%b3%bb%e5%88%97%ef%bc%88%e4%ba%ba%e5%ad%97%e6%8b%bc%ef%bc%89\/%e9%9b%b2%e6%bc%ab%e9%9b%aa%e5%b1%b1%e4%ba%ba%e5%ad%97%e6%8b%bc\/","title":{"rendered":"\u96f2\u6f2b\u96ea\u5c71(\u4eba\u5b57\u62fc)"},"content":{"rendered":"<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-ac3ebc3b wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-content-justification-left is-layout-constrained wp-container-core-column-is-layout-02d07192 wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">\u96f2\u6f2b\u96ea\u5c71(\u4eba\u5b57\u62fc)<\/h2>\n\n\n\n<p>NL-XMJ-SPC-YUN-003-RZP<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p>\u7522\u54c1\u5c3a\u5bf8\uff1a<\/p>\n\n\n\n<p>635 x 127 x 6.0 mm<\/p>\n\n\n\n<p>\u7522\u54c1\u7d50\u69cb\uff1a<\/p>\n\n\n\n<p>5 mm \u2013 \u9ad8\u79d1\u6280\u9632\u6c34\u6297\u8150\u77f3\u6676\u5c64<\/p>\n\n\n\n<p>1.0 mm \u2013 IXPE\u6297\u6c34\u975c\u97f3\u5c64<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"434\" height=\"1024\" data-id=\"859\" src=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-54-434x1024.png\" alt=\"\" class=\"wp-image-859\" srcset=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-54-434x1024.png 434w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-54-127x300.png 127w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-54-768x1812.png 768w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-54-651x1536.png 651w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-54-868x2048.png 868w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-54-5x12.png 5w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-54.png 937w\" sizes=\"auto, (max-width: 434px) 100vw, 434px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"765\" height=\"1024\" data-id=\"860\" src=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-53-3-765x1024.png\" alt=\"\" class=\"wp-image-860\" srcset=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-53-3-765x1024.png 765w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-53-3-224x300.png 224w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-53-3-768x1029.png 768w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-53-3-1147x1536.png 1147w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-53-3-1529x2048.png 1529w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-53-3-9x12.png 9w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-53-3.png 1792w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"765\" data-id=\"861\" src=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-52-1024x765.png\" alt=\"\" class=\"wp-image-861\" srcset=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-52-1024x765.png 1024w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-52-300x224.png 300w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-52-768x573.png 768w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-52-1536x1147.png 1536w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-52-2048x1529.png 2048w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-52-16x12.png 16w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-52-402x300.png 402w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>\u96f2\u6f2b\u96ea\u5c71(\u4eba\u5b57\u62fc) NL-XMJ-SPC-YUN- &hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":896,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-858","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages\/858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/comments?post=858"}],"version-history":[{"count":1,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages\/858\/revisions"}],"predecessor-version":[{"id":862,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages\/858\/revisions\/862"}],"up":[{"embeddable":true,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages\/896"}],"wp:attachment":[{"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/media?parent=858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}