{"id":782,"date":"2026-06-22T05:21:23","date_gmt":"2026-06-22T05:21:23","guid":{"rendered":"https:\/\/nolabelworld.com\/?page_id=782"},"modified":"2026-06-22T06:47:40","modified_gmt":"2026-06-22T06:47:40","slug":"%e7%91%9e%e5%90%89%e6%99%a8%e6%9b%a6","status":"publish","type":"page","link":"https:\/\/nolabelworld.com\/zh_cn\/%e8%ab%be%e8%90%8a%e5%b1%85spc%e5%9c%b0%e6%9d%bf%e7%b3%bb%e5%88%97\/%e6%9c%a8%e7%b3%bb%e5%88%97\/%e7%91%9e%e5%90%89%e6%99%a8%e6%9b%a6\/","title":{"rendered":"\u745e\u5409\u6668\u66e6"},"content":{"rendered":"<div class=\"wp-block-columns alignwide are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-ac3ebc3b wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-content-justification-left is-layout-constrained wp-container-core-column-is-layout-02d07192 wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">\u745e\u5409\u6668\u66e6<\/h2>\n\n\n\n<p>NL-XMJ-SPC-RUI-003<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p>\u7522\u54c1\u5c3a\u5bf8\uff1a<\/p>\n\n\n\n<p>1220 x 182 x 6.5\/8.0 mm<\/p>\n\n\n\n<p>\u7522\u54c1\u7d50\u69cb\uff1a<\/p>\n\n\n\n<p>5 mm \/ 6 mm \u2013 \u9ad8\u79d1\u6280\u9632\u6c34\u6297\u8150\u77f3\u6676\u5c64<\/p>\n\n\n\n<p>1.5 mm \/ 2.0 mm -IXPE\u6297\u6c34\u975c\u97f3\u5c64<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"1024\" data-id=\"783\" src=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-15-512x1024.png\" alt=\"\" class=\"wp-image-783\" srcset=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-15-512x1024.png 512w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-15-150x300.png 150w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-15-768x1536.png 768w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-15-1024x2048.png 1024w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-15-6x12.png 6w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-15.png 1080w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"765\" height=\"1024\" data-id=\"784\" src=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-14-3-765x1024.png\" alt=\"\" class=\"wp-image-784\" srcset=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-14-3-765x1024.png 765w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-14-3-224x300.png 224w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-14-3-768x1029.png 768w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-14-3-1147x1536.png 1147w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-14-3-1529x2048.png 1529w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-14-3-9x12.png 9w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-14-3.png 1792w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"765\" src=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-13-1024x765.png\" alt=\"\" class=\"wp-image-785\" srcset=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-13-1024x765.png 1024w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-13-300x224.png 300w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-13-768x573.png 768w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-13-1536x1147.png 1536w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-13-2048x1529.png 2048w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-13-16x12.png 16w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-13-402x300.png 402w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>\u745e\u5409\u6668\u66e6 NL-XMJ-SPC-RUI-003 \u7522 &hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":655,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-782","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages\/782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/comments?post=782"}],"version-history":[{"count":1,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages\/782\/revisions"}],"predecessor-version":[{"id":786,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages\/782\/revisions\/786"}],"up":[{"embeddable":true,"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/pages\/655"}],"wp:attachment":[{"href":"https:\/\/nolabelworld.com\/zh_cn\/wp-json\/wp\/v2\/media?parent=782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}