{"id":879,"date":"2026-06-22T06:33:31","date_gmt":"2026-06-22T06:33:31","guid":{"rendered":"https:\/\/nolabelworld.com\/?page_id=879"},"modified":"2026-06-22T06:52:57","modified_gmt":"2026-06-22T06:52:57","slug":"%e9%bb%91%e6%9b%9c%e6%9c%88%e7%b4%8b%ef%bc%88%e4%ba%ba%e5%ad%97%e6%8b%bc%ef%bc%89","status":"publish","type":"page","link":"https:\/\/nolabelworld.com\/en\/%e8%ab%be%e8%90%8a%e5%b1%85spc%e5%9c%b0%e6%9d%bf%e7%b3%bb%e5%88%97\/%e6%9c%a8%e7%b3%bb%e5%88%97%ef%bc%88%e4%ba%ba%e5%ad%97%e6%8b%bc%ef%bc%89\/%e9%bb%91%e6%9b%9c%e6%9c%88%e7%b4%8b%ef%bc%88%e4%ba%ba%e5%ad%97%e6%8b%bc%ef%bc%89\/","title":{"rendered":"Black Obsidian Moon Pattern (Herringbone Stitch)"},"content":{"rendered":"<div class=\"wp-block-columns are-vertically-aligned-top is-layout-flex wp-container-core-columns-is-layout-ac3ebc3b wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-content-justification-left is-layout-constrained wp-container-core-column-is-layout-02d07192 wp-block-column-is-layout-constrained\">\n<h2 class=\"wp-block-heading\">Black Obsidian Moon Pattern (Herringbone Stitch)<\/h2>\n\n\n\n<p>NL-XMJ-SPC-YUE-001-RZP<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\">\n<p>Product Dimensions:<\/p>\n\n\n\n<p>635 x 127 x 6.0 mm<\/p>\n\n\n\n<p>Product Structure:<\/p>\n\n\n\n<p>5 mm \u2013 High-tech waterproof and corrosion-resistant stone crystal layer<\/p>\n\n\n\n<p>1.0 mm \u2013 IXPE water-resistant sound-dampening layer<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"433\" height=\"1024\" data-id=\"880\" src=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-66-433x1024.png\" alt=\"\" class=\"wp-image-880\" srcset=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-66-433x1024.png 433w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-66-127x300.png 127w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-66-768x1818.png 768w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-66-649x1536.png 649w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-66-865x2048.png 865w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-66-5x12.png 5w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-66.png 904w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"765\" height=\"1024\" data-id=\"881\" src=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-64-3-765x1024.png\" alt=\"\" class=\"wp-image-881\" srcset=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-64-3-765x1024.png 765w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-64-3-224x300.png 224w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-64-3-768x1029.png 768w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-64-3-1147x1536.png 1147w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-64-3-1529x2048.png 1529w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-64-3-9x12.png 9w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-64-3.png 1792w\" sizes=\"auto, (max-width: 765px) 100vw, 765px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"765\" data-id=\"882\" src=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-65-1024x765.png\" alt=\"\" class=\"wp-image-882\" srcset=\"https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-65-1024x765.png 1024w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-65-300x224.png 300w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-65-768x573.png 768w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-65-1536x1147.png 1536w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-65-2048x1529.png 2048w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-65-16x12.png 16w, https:\/\/nolabelworld.com\/wp-content\/uploads\/2026\/06\/\u56fe\u7247-65-402x300.png 402w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>\u9ed1\u66dc\u6708\u7d0b\uff08\u4eba\u5b57\u62fc\uff09 NL-XMJ-SPC-YUE- &hellip;<\/p>","protected":false},"author":1,"featured_media":0,"parent":896,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-879","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nolabelworld.com\/en\/wp-json\/wp\/v2\/pages\/879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nolabelworld.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nolabelworld.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nolabelworld.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nolabelworld.com\/en\/wp-json\/wp\/v2\/comments?post=879"}],"version-history":[{"count":1,"href":"https:\/\/nolabelworld.com\/en\/wp-json\/wp\/v2\/pages\/879\/revisions"}],"predecessor-version":[{"id":883,"href":"https:\/\/nolabelworld.com\/en\/wp-json\/wp\/v2\/pages\/879\/revisions\/883"}],"up":[{"embeddable":true,"href":"https:\/\/nolabelworld.com\/en\/wp-json\/wp\/v2\/pages\/896"}],"wp:attachment":[{"href":"https:\/\/nolabelworld.com\/en\/wp-json\/wp\/v2\/media?parent=879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}